{"id":2,"count":2,"description":"This page provides","link":"https:\/\/blogs.ncl.ac.uk\/geosciencesresearchgroupblog\/category\/fieldwork\/","name":"Fieldwork","slug":"fieldwork","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ncl.ac.uk\/geosciencesresearchgroupblog\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ncl.ac.uk\/geosciencesresearchgroupblog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.ncl.ac.uk\/geosciencesresearchgroupblog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.ncl.ac.uk\/geosciencesresearchgroupblog\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}