{"id":6262,"name":"nno11","url":"","description":"","link":"https:\/\/blogs.ncl.ac.uk\/nuren\/author\/nno11\/","slug":"nno11","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ncl.ac.uk\/nuren\/wp-json\/wp\/v2\/users\/6262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ncl.ac.uk\/nuren\/wp-json\/wp\/v2\/users"}]}}